{"id":12,"date":"2022-04-12T16:48:01","date_gmt":"2022-04-12T16:48:01","guid":{"rendered":"https:\/\/trasteros.napodonosti.com\/?page_id=12"},"modified":"2022-04-16T16:56:51","modified_gmt":"2022-04-16T16:56:51","slug":"home","status":"publish","type":"page","link":"https:\/\/trasteros.napodonosti.com\/","title":{"rendered":"Entrada"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light hestia-clear-top-padding\"><span aria-hidden=\"true\" class=\"has-white-background-color has-background-dim-100 wp-block-cover__gradient-background has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h2 class=\"has-text-align-center has-text-color has-x-large-font-size wp-block-heading\" style=\"color:#3c4858\">Entrada<\/h2>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns container is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image is-style-rounded\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_182032-1024x768.jpg\" alt=\"\" class=\"wp-image-38\" srcset=\"https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_182032-1024x768.jpg 1024w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_182032-300x225.jpg 300w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_182032-768x576.jpg 768w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_182032-1536x1152.jpg 1536w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_182032-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"has-text-align-center has-text-color has-medium-font-size wp-block-heading\" style=\"color:#3c4858\">\u00a1Entrada directa!<\/h5>\n\n\n\n<p class=\"has-text-align-center has-text-color wp-block-paragraph\" style=\"color:#999999;font-size:16px\">Entrada propia desde la calle Marina. No tendr\u00e1s que entrar desde ning\u00fan portal, ya que esta entrada es exclusiva para los trasteros.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image is-style-rounded\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_180053-1024x768.jpg\" alt=\"\" class=\"wp-image-41\" srcset=\"https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_180053-1024x768.jpg 1024w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_180053-300x225.jpg 300w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_180053-768x576.jpg 768w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_180053-1536x1152.jpg 1536w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_180053-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"has-text-align-center has-text-color has-medium-font-size wp-block-heading\" style=\"color:#3c4858\">En el mismo centro<\/h5>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#999999;font-size:16px\">Pegado a la calle San Martin. A podos metros de la playa de la concha y cerca de todo el centro de Donostia<a href=\"#blog\" data-type=\"internal\" data-id=\"#blog\">.<\/a><\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image is-style-rounded\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_192710-1024x768.jpg\" alt=\"\" class=\"wp-image-48\" srcset=\"https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_192710-1024x768.jpg 1024w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_192710-300x225.jpg 300w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_192710-768x576.jpg 768w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_192710-1536x1152.jpg 1536w, https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/IMG_20220412_192710-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"has-text-align-center has-text-color has-medium-font-size wp-block-heading\" style=\"color:#3c4858\">Pasillo bien iluminado.<\/h5>\n\n\n\n<p class=\"has-text-align-center has-text-color wp-block-paragraph\" style=\"color:#999999;font-size:16px\">Para que puedas acceder a tu trastero con total seguridad.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns container is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col-md-5 is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-left wp-block-heading\">\u00a1M\u00e1s informaci\u00f3n!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfNecesitas m\u00e1s informaci\u00f3n?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfConcertar una cita?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llama o manda un whatsapp al siguiente n\u00famero.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image is-style-rounded\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/trasteros.napodonosti.com\/wp-content\/uploads\/2022\/04\/whatsapp.jpeg\" alt=\"\" class=\"wp-image-59\" width=\"129\" height=\"129\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom col-md-6 col-md-offset1 is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"has-text-align-center has-x-large-font-size wp-block-heading\">646505617<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Si lo prefieres puedes utilizar el formulario de contacto a pie de pagina para mandar un mensaje.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-accent-background-color has-background\" href=\"#contact\">Formulario<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1M\u00e1s informaci\u00f3n! \u00bfNecesitas m\u00e1s informaci\u00f3n? \u00bfConcertar una cita? Llama o manda un whatsapp al siguiente n\u00famero. 646505617 Si lo prefieres puedes utilizar el formulario de contacto a pie de pagina para mandar un mensaje.<\/p>\n","protected":false},"author":1,"featured_media":78,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/trasteros.napodonosti.com\/index.php\/wp-json\/wp\/v2\/pages\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trasteros.napodonosti.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/trasteros.napodonosti.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/trasteros.napodonosti.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trasteros.napodonosti.com\/index.php\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":16,"href":"https:\/\/trasteros.napodonosti.com\/index.php\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":146,"href":"https:\/\/trasteros.napodonosti.com\/index.php\/wp-json\/wp\/v2\/pages\/12\/revisions\/146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trasteros.napodonosti.com\/index.php\/wp-json\/wp\/v2\/media\/78"}],"wp:attachment":[{"href":"https:\/\/trasteros.napodonosti.com\/index.php\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}